{"id":12047,"date":"2015-12-26T08:20:53","date_gmt":"2015-12-26T08:20:53","guid":{"rendered":"https:\/\/genomecanada.ca\/drupal\/news_release\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\/"},"modified":"2024-01-16T08:35:27","modified_gmt":"2024-01-16T13:35:27","slug":"genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada","status":"publish","type":"post","link":"https:\/\/genomecanada.ca\/fr\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\/","title":{"rendered":"G\u00e9nome Canada annonce le nouveau R\u00e9seau d\u2019innovation g\u00e9nomique du Canada"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"12047\" class=\"elementor elementor-12047\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-373bd412 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"80034\" data-id=\"373bd412\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-28c0040a\" data-eae-slider=\"39319\" data-id=\"28c0040a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57393d33 elementor-widget elementor-widget-text-editor\" data-id=\"57393d33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>G\u00e9nome Canada est heureuse d\u2019annoncer un investissement de 15,5 millions de dollars dans le nouveau R\u00e9seau d\u2019innovation g\u00e9nomique du Canada. Les dix \u00ab p\u00f4les \u00bb qui composent ce r\u00e9seau recevront de G\u00e9nome Canada des fonds pour soutenir leur fonctionnement de base, de m\u00eame que des fonds de contrepartie de divers partenaires des secteurs public et priv\u00e9.<\/p>\n<p>Le R\u00e9seau d\u2019innovation g\u00e9nomique est con\u00e7u pour la collaboration et la mise en commun du pouvoir collectif des centres d\u2019innovation canadiens au profit de la recherche en g\u00e9nomique. Chaque p\u00f4le fournit aux chercheurs canadiens et internationaux acc\u00e8s aux technologies de pointe dont ils ont besoin pour leurs travaux de recherche en g\u00e9nomique, en m\u00e9tabolomique, en prot\u00e9omique et dans les domaines connexes. Ces p\u00f4les sont \u00e9galement bien plac\u00e9s pour repousser les limites et mettre au point de nouvelles technologies en g\u00e9nomique et dans les sciences connexes.<\/p>\n<p>Le personnel hautement qualifi\u00e9 de chaque p\u00f4le mettra en outre ses comp\u00e9tences sp\u00e9cialis\u00e9es au service des chercheurs canadiens et les conseillera sur l\u2019utilisation et le choix des technologies appropri\u00e9es, la conception d\u2019\u00e9tudes, l\u2019analyse des donn\u00e9es et la bio-informatique pour que la recherche canadienne demeure de calibre mondial et des plus concurrentielle \u00e0 l\u2019\u00e9chelle internationale.<\/p>\n<h4><strong>Faits en bref<\/strong><\/h4>\n<ul>\n<li>Le gouvernement f\u00e9d\u00e9ral, par le truchement de G\u00e9nome Canada, investit initialement 15,5 millions de dollars dans le fonctionnement de base des 10 p\u00f4les. Chacun recevra de 800 000 $ \u00e0 2 000 000 $ des fonds f\u00e9d\u00e9raux sur une p\u00e9riode de deux ans \u00e0 compter du 1er avril 2015. Les investissements de cobailleurs de fonds partenaires, dont les gouvernements provinciaux, des \u00e9tablissements universitaires et le secteur priv\u00e9 dans un rapport minimum obligatoire de 1 sur 1, porteront le total des investissements initiaux dans le R\u00e9seau d\u2019innovation g\u00e9nomique \u00e0 31 millions de dollars environ.<\/li>\n<li>De plus, environ 15 millions de dollars seront investis dans les p\u00f4les au cours des deux prochaines ann\u00e9es. La majeure partie de ces fonds servira \u00e0 la mise au point de technologies et \u00e0 des projets de collaboration. Ces investissements additionnels attireront \u00e9galement un montant au moins \u00e9gal en cofinancement de partenaires des secteurs public et priv\u00e9.<\/li>\n<li>Les p\u00f4les ont \u00e9t\u00e9 choisis \u00e0 la suite d\u2019un concours dans le cadre duquel les propositions ont \u00e9t\u00e9 soumises \u00e0 un examen par les pairs, effectu\u00e9 par un comit\u00e9 international d\u2019\u00e9valuation.<\/li>\n<li>Le R\u00e9seau d\u2019innovation g\u00e9nomique est un nouveau mod\u00e8le qui remplace les investissements pr\u00e9c\u00e9dents de G\u00e9nome Canada dans cinq centres d\u2019innovation de sciences et de technologie. Le nouveau mod\u00e8le de r\u00e9seau met davantage l\u2019accent sur la collaboration et l\u2019\u00e9change des comp\u00e9tences entre les poles.<\/li>\n<li>Assurer aux chercheurs canadiens l\u2019acc\u00e8s \u00e0 des technologies d\u2019avant-garde est l\u2019un des fondements du mandat de G\u00e9nome Canada. La cr\u00e9ation du R\u00e9seau d\u2019innovation g\u00e9nomique contribuera \u00e0 renforcer le r\u00f4le de chef de file du Canada dans la mise au point de nouvelles technologies g\u00e9nomiques de rupture. L\u2019investissement appuiera en outre des travaux importants dans les domaines de la bio-informatique et de la g\u00e9n\u00e9matique, entre autres r\u00e9soudre les grands d\u00e9fis que posent le stockage et l\u2019analyse des donn\u00e9es volumineuses.<\/li>\n<\/ul>\n<h4><strong>Citations<\/strong><\/h4>\n<p>\u00ab Dans le cadre de la phase suivante de notre Plan d\u2019action \u00e9conomique \u2013 Des imp\u00f4ts bas pour stimuler la croissance et l\u2019emploi, nous avons fait des investissements sans pr\u00e9c\u00e9dent dans les sciences et la technologie au Canada, y compris \u00e0 G\u00e9nome Canada. Le nouveau R\u00e9seau d\u2019innovation g\u00e9nomique de G\u00e9nome Canada fournira aux chercheurs canadiens de haut niveau les nouvelles connaissances et les nouveaux outils dont ils ont besoin pour faire des d\u00e9couvertes r\u00e9volutionnaires \u2013 des d\u00e9couvertes qui cr\u00e9eront des emplois et la prosp\u00e9rit\u00e9 et qui am\u00e9lioreront la qualit\u00e9 de vie de toute la population canadienne. \u00bb<br><span style=\"font-size: 18px;\">&#8211; L\u2019honorable Ed Holder, ministre d\u2019\u00c9tat, Sciences et Technologie<\/span><\/p>\n<p>\u00ab Les perc\u00e9es dans tous les secteurs de la bio\u00e9conomie en expansion au Canada, soit la sant\u00e9, l\u2019agriculture, les p\u00eaches et l\u2019aquaculture, la foresterie, l\u2019\u00e9nergie et les mines, d\u00e9pendent de l\u2019acc\u00e8s des chercheurs canadiens aux technologies de pointe en sciences \u00ab\u00a0omiques\u00a0\u00bb qui ne cessent d\u2019\u00e9voluer. De plus, nous voulons miser sur les r\u00e9ussites ant\u00e9rieures qui montrent que les nouvelles technologies g\u00e9nomiques deviennent le fondement de la croissance des entreprises canadiennes.\u00bb<br><span style=\"font-size: 18px;\">&#8211; M. Pierre Meulien, pr\u00e9sident et chef de la direction, G\u00e9nome Canada<\/span><\/p>\n<h4>Renseignements<\/h4>\n<p>Andrea Matyas<br>Directrice, Communications<br>G\u00e9nome Canada<br>Bureau : 613-751-4460, poste 231<br>Cell. : 613-790-0106<\/p>\n<h4>\u00c0 propos de G\u00e9nome Canada<\/h4>\n<p>G\u00e9nome Canada est un organisme sans but lucratif qui joue un r\u00f4le de catalyseur dans l\u2019\u00e9laboration et l\u2019application de la g\u00e9nomique et des technologies bas\u00e9es sur la g\u00e9nomique dans de nombreux secteurs pour cr\u00e9er des avantages \u00e9conomiques et sociaux pour la population canadienne. Pour plus de renseignements, visitez www.genomecanada.ca.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>G\u00e9nome Canada est heureuse d\u2019annoncer un investissement de 15,5 millions de dollars dans le nouveau R\u00e9seau d\u2019innovation g\u00e9nomique du Canada. Les dix \u00ab p\u00f4les \u00bb qui composent ce r\u00e9seau recevront de G\u00e9nome Canada des fonds pour soutenir leur fonctionnement de base, de m\u00eame que des fonds de contrepartie de divers partenaires des secteurs public et [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[127],"tags":[],"mission-categories":[],"class_list":["post-12047","post","type-post","status-publish","format-standard","hentry","category-news-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>G\u00e9nome Canada annonce le nouveau R\u00e9seau d\u2019innovation g\u00e9nomique du Canada - GenomeCanada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/genomecanada.ca\/fr\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"G\u00e9nome Canada annonce le nouveau R\u00e9seau d\u2019innovation g\u00e9nomique du Canada - GenomeCanada\" \/>\n<meta property=\"og:description\" content=\"G\u00e9nome Canada est heureuse d\u2019annoncer un investissement de 15,5 millions de dollars dans le nouveau R\u00e9seau d\u2019innovation g\u00e9nomique du Canada. Les dix \u00ab p\u00f4les \u00bb qui composent ce r\u00e9seau recevront de G\u00e9nome Canada des fonds pour soutenir leur fonctionnement de base, de m\u00eame que des fonds de contrepartie de divers partenaires des secteurs public et [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/genomecanada.ca\/fr\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\/\" \/>\n<meta property=\"og:site_name\" content=\"GenomeCanada\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-26T08:20:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-16T13:35:27+00:00\" \/>\n<meta name=\"author\" content=\"Pierre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\\\/\"},\"author\":{\"name\":\"Pierre\",\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/#\\\/schema\\\/person\\\/9178d2ca6aca04c78924c5863c96697a\"},\"headline\":\"G\u00e9nome Canada annonce le nouveau R\u00e9seau d\u2019innovation g\u00e9nomique du Canada\",\"datePublished\":\"2015-12-26T08:20:53+00:00\",\"dateModified\":\"2024-01-16T13:35:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\\\/\"},\"wordCount\":858,\"publisher\":{\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/#organization\"},\"articleSection\":[\"News\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\\\/\",\"url\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\\\/\",\"name\":\"G\u00e9nome Canada annonce le nouveau R\u00e9seau d\u2019innovation g\u00e9nomique du Canada - GenomeCanada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/#website\"},\"datePublished\":\"2015-12-26T08:20:53+00:00\",\"dateModified\":\"2024-01-16T13:35:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"G\u00e9nome Canada annonce le nouveau R\u00e9seau d\u2019innovation g\u00e9nomique du Canada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/\",\"name\":\"GenomeCanada\",\"description\":\"Harnessing the transformative power of genomics\",\"publisher\":{\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/#organization\",\"name\":\"GenomeCanada\",\"url\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/genomecanada.ca\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/genome-canada_stacked.svg\",\"contentUrl\":\"https:\\\/\\\/genomecanada.ca\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/genome-canada_stacked.svg\",\"width\":285,\"height\":180,\"caption\":\"GenomeCanada\"},\"image\":{\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/#\\\/schema\\\/person\\\/9178d2ca6aca04c78924c5863c96697a\",\"name\":\"Pierre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a57e4d6e69393a17b8cd7f6418130969ad93131795406009ba79ed41978382d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a57e4d6e69393a17b8cd7f6418130969ad93131795406009ba79ed41978382d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a57e4d6e69393a17b8cd7f6418130969ad93131795406009ba79ed41978382d2?s=96&d=mm&r=g\",\"caption\":\"Pierre\"},\"url\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/author\\\/pierre\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"G\u00e9nome Canada annonce le nouveau R\u00e9seau d\u2019innovation g\u00e9nomique du Canada - GenomeCanada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/genomecanada.ca\/fr\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\/","og_locale":"fr_FR","og_type":"article","og_title":"G\u00e9nome Canada annonce le nouveau R\u00e9seau d\u2019innovation g\u00e9nomique du Canada - GenomeCanada","og_description":"G\u00e9nome Canada est heureuse d\u2019annoncer un investissement de 15,5 millions de dollars dans le nouveau R\u00e9seau d\u2019innovation g\u00e9nomique du Canada. Les dix \u00ab p\u00f4les \u00bb qui composent ce r\u00e9seau recevront de G\u00e9nome Canada des fonds pour soutenir leur fonctionnement de base, de m\u00eame que des fonds de contrepartie de divers partenaires des secteurs public et [&hellip;]","og_url":"https:\/\/genomecanada.ca\/fr\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\/","og_site_name":"GenomeCanada","article_published_time":"2015-12-26T08:20:53+00:00","article_modified_time":"2024-01-16T13:35:27+00:00","author":"Pierre","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Pierre","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/genomecanada.ca\/fr\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\/#article","isPartOf":{"@id":"https:\/\/genomecanada.ca\/fr\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\/"},"author":{"name":"Pierre","@id":"https:\/\/genomecanada.ca\/fr\/#\/schema\/person\/9178d2ca6aca04c78924c5863c96697a"},"headline":"G\u00e9nome Canada annonce le nouveau R\u00e9seau d\u2019innovation g\u00e9nomique du Canada","datePublished":"2015-12-26T08:20:53+00:00","dateModified":"2024-01-16T13:35:27+00:00","mainEntityOfPage":{"@id":"https:\/\/genomecanada.ca\/fr\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\/"},"wordCount":858,"publisher":{"@id":"https:\/\/genomecanada.ca\/fr\/#organization"},"articleSection":["News"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/genomecanada.ca\/fr\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\/","url":"https:\/\/genomecanada.ca\/fr\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\/","name":"G\u00e9nome Canada annonce le nouveau R\u00e9seau d\u2019innovation g\u00e9nomique du Canada - GenomeCanada","isPartOf":{"@id":"https:\/\/genomecanada.ca\/fr\/#website"},"datePublished":"2015-12-26T08:20:53+00:00","dateModified":"2024-01-16T13:35:27+00:00","breadcrumb":{"@id":"https:\/\/genomecanada.ca\/fr\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/genomecanada.ca\/fr\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/genomecanada.ca\/fr\/genome-canada-annonce-le-nouveau-reseau-dinnovation-genomique-du-canada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/genomecanada.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"G\u00e9nome Canada annonce le nouveau R\u00e9seau d\u2019innovation g\u00e9nomique du Canada"}]},{"@type":"WebSite","@id":"https:\/\/genomecanada.ca\/fr\/#website","url":"https:\/\/genomecanada.ca\/fr\/","name":"GenomeCanada","description":"Harnessing the transformative power of genomics","publisher":{"@id":"https:\/\/genomecanada.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/genomecanada.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/genomecanada.ca\/fr\/#organization","name":"GenomeCanada","url":"https:\/\/genomecanada.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/genomecanada.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/genomecanada.ca\/wp-content\/uploads\/2021\/07\/genome-canada_stacked.svg","contentUrl":"https:\/\/genomecanada.ca\/wp-content\/uploads\/2021\/07\/genome-canada_stacked.svg","width":285,"height":180,"caption":"GenomeCanada"},"image":{"@id":"https:\/\/genomecanada.ca\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/genomecanada.ca\/fr\/#\/schema\/person\/9178d2ca6aca04c78924c5863c96697a","name":"Pierre","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a57e4d6e69393a17b8cd7f6418130969ad93131795406009ba79ed41978382d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a57e4d6e69393a17b8cd7f6418130969ad93131795406009ba79ed41978382d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a57e4d6e69393a17b8cd7f6418130969ad93131795406009ba79ed41978382d2?s=96&d=mm&r=g","caption":"Pierre"},"url":"https:\/\/genomecanada.ca\/fr\/author\/pierre\/"}]}},"_links":{"self":[{"href":"https:\/\/genomecanada.ca\/fr\/wp-json\/wp\/v2\/posts\/12047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/genomecanada.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/genomecanada.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/genomecanada.ca\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/genomecanada.ca\/fr\/wp-json\/wp\/v2\/comments?post=12047"}],"version-history":[{"count":0,"href":"https:\/\/genomecanada.ca\/fr\/wp-json\/wp\/v2\/posts\/12047\/revisions"}],"wp:attachment":[{"href":"https:\/\/genomecanada.ca\/fr\/wp-json\/wp\/v2\/media?parent=12047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/genomecanada.ca\/fr\/wp-json\/wp\/v2\/categories?post=12047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/genomecanada.ca\/fr\/wp-json\/wp\/v2\/tags?post=12047"},{"taxonomy":"mission-categories","embeddable":true,"href":"https:\/\/genomecanada.ca\/fr\/wp-json\/wp\/v2\/mission-categories?post=12047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}