{"id":1454,"date":"2015-12-26T07:24:04","date_gmt":"2015-12-26T07:24:04","guid":{"rendered":"https:\/\/genomecanada.ca\/drupal\/news_release\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\/"},"modified":"2015-12-26T07:24:04","modified_gmt":"2015-12-26T07:24:04","slug":"de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et","status":"publish","type":"post","link":"https:\/\/genomecanada.ca\/fr\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\/","title":{"rendered":"De nouveaux projets de recherche en g\u00e9nomique cr\u00e9eront des avantages \u00e9conomiques et sociaux pour la population canadienne"},"content":{"rendered":"<p>Des milliers de patients canadiens atteints de cancer pourraient bient\u00f4t b\u00e9n\u00e9ficier d\u2019un traitement plus cibl\u00e9 et personnalis\u00e9 gr\u00e2ce \u00e0 un investissement de G\u00e9nome Canada.<\/p>\n<p>L\u2019honorable Ed Holder, ministre d\u2019\u00c9tat (Sciences et Technologie) et M. Bernard Trottier, d\u00e9put\u00e9 d\u2019Etobicoke Lakeshore, accompagn\u00e9s de M. Lorne Hepworth, pr\u00e9sident d\u2019assembl\u00e9e de G\u00e9nome Canada, ont annonc\u00e9 l\u2019investissement de pr\u00e8s de 16 millions de dollars dans quatre nouveaux projets de recherche qui constituent la troisi\u00e8me s\u00e9rie du Programme des partenariats pour les applications de la g\u00e9nomique de G\u00e9nome Canada (PPAG). L\u2019annonce s\u2019est faite au Princess Margaret Cancer Centre o\u00f9 le ministre, M. Trottier et M. Hepworth ont visit\u00e9 le laboratoire de la chercheuse en cancer et g\u00e9n\u00e9ticienne en laboratoire clinique, Dre Suzanne Kamel-Reid.<\/p>\n<p>La Dre Kamel-Reid travaillera en collaboration avec LifeLabs Medical Laboratory Services \u00e0 l\u2019\u00e9laboration d\u2019un programme de personnalisation des traitements du cancer gr\u00e2ce au profilage g\u00e9nomique, ce qui pourrait sauver des milliers de vies. En cr\u00e9ant un profil g\u00e9nomique de divers cancers, les professionnels de la sant\u00e9 peuvent offrir le bon m\u00e9dicament au bon moment \u00e0 un patient, ce qui am\u00e9liorera les r\u00e9sultats des traitements anticanc\u00e9reux fournis aux Canadiennes et aux Canadiens, d\u2019un bout \u00e0 l\u2019autre du pays. De plus, l\u2019infrastructure implant\u00e9e dans le cadre du projet repr\u00e9sente un progr\u00e8s consid\u00e9rable vers des \u00e9conomies substantielles pour le syst\u00e8me de sant\u00e9, pour de nombreux types de cancer.<\/p>\n<p>Les projets du PPAG se caract\u00e9risent par la collaboration de chercheurs universitaires et d\u2019\u00ab utilisateurs \u00bb de la g\u00e9nomique (p. ex., l\u2019industrie, les gouvernements provinciaux, les organismes sans but lucratif et d\u2019autres organisations) qui mettent au point des innovations qui pourraient avoir des r\u00e9percussions \u00e9conomiques et sociales consid\u00e9rables \u00e0 court terme.<\/p>\n<p>Les autres projets annonc\u00e9s dans cette troisi\u00e8me s\u00e9rie du Programme comprennent l\u2019utilisation de la g\u00e9nomique pour am\u00e9liorer l\u2019huile de soya \u00e0 des fins commerciales; l\u2019am\u00e9lioration des r\u00e9sultats pour les patients qui ont re\u00e7u une greffe du poumon; et la culture de conif\u00e8res plus r\u00e9silients et de meilleure qualit\u00e9 pour que l\u2019industrie foresti\u00e8re canadienne exerce une concurrence plus efficace \u00e0 l\u2019\u00e9chelle mondiale.<\/p>\n<p><strong>Faits rapides<\/strong><\/p>\n<ul>\n<li>Environ 200 000 Canadiennes et Canadiens re\u00e7oivent un diagnostic de cancer annuellement. Plus d\u2019un patient sur quatre d\u2019entre eux profiterait du profilage g\u00e9nomique, rapide et complet, du cancer.<\/li>\n<li>Selon un nouveau projet financ\u00e9 par le PPAG, les chercheurs du Princess Margaret Cancer Centre s\u2019associeront \u00e0 LifeLabs Medical Laboratory Services pour accro\u00eetre le nombre de patients qui ont acc\u00e8s \u00e0 ce profilage g\u00e9nomique complet du cancer.<\/li>\n<li>Les quatre projets annonc\u00e9s aujourd\u2019hui repr\u00e9sentent un investissement total de 15,7 millions de dollars. Le gouvernement du Canada verse 5,2 millions de dollars par le truchement de G\u00e9nome Canada et le reste (environ 10,5 millions de dollars) provient de partenaires du cofinancement, notamment des \u00ab utilisateurs \u00bb de la g\u00e9nomique. Douze projets ont \u00e9t\u00e9 pr\u00e9c\u00e9demment financ\u00e9s dans les deux premi\u00e8res s\u00e9ries du Programme.<\/li>\n<li>Les projets annonc\u00e9s aujourd\u2019hui sont men\u00e9s par des chercheurs dont les \u00e9tablissements sont situ\u00e9s en Ontario (Princess Margaret Cancer Centre [PMCC], Universit\u00e9 de Toronto), au Qu\u00e9bec (Universit\u00e9 Laval) et en Alberta (Universit\u00e9 de l\u2019Alberta). Leurs partenaires proviennent des secteurs de l\u2019agriculture, des soins de sant\u00e9 et de la foresterie. (Lire les descriptions des projets dans la&nbsp;<a href=\"http:\/\/www.genomecanada.ca\/medias\/pdf\/fr\/gapp-backgrounder-round3-projects_FR.pdf\">fiche d\u2019information<\/a>.)<\/li>\n<li>Lanc\u00e9 en 2013, le PPAG est un programme de 113 millions de dollars, dont 37,8 millions de dollars proviennent du gouvernement f\u00e9d\u00e9ral, par le truchement de G\u00e9nome Canada, et le reste, d\u2019investisseurs partenaires (soit l\u2019industrie, le gouvernement, les organismes sans but lucratif et d\u2019autres).<\/li>\n<\/ul>\n<p><strong>Citations<\/strong><\/p>\n<p>\u00ab Notre gouvernement est r\u00e9solu \u00e0 acc\u00e9l\u00e9rer la transition des id\u00e9es du laboratoire au march\u00e9 afin de cr\u00e9er des entreprises canadiennes plus concurrentielles \u00e0 l\u2019\u00e9chelle mondiale et des emplois ici m\u00eame au pays. Notre investissement dans le Programme des partenariats pour les applications de la g\u00e9nomique appuie ces partenariats pour trouver des solutions g\u00e9nomiques \u00e0 des difficult\u00e9s bien concr\u00e8tes et cr\u00e9er \u00e0 la fois des avantages sociaux et \u00e9conomiques pour la population canadienne. \u00bb<\/p>\n<p>\u2013 L\u2019honorable Ed Holder, ministre d\u2019\u00c9tat, Sciences et Technologie<\/p>\n<p>\u00ab Notre gouvernement a investi des sommes records en sciences, en technologie et en innovation pour cr\u00e9er des emplois et de la prosp\u00e9rit\u00e9, et pour am\u00e9liorer la vie de toute la population canadienne. L\u2019investissement d\u2019aujourd\u2019hui dans le projet du PPAG men\u00e9 par le Princess Margaret Cancer Centre et LifeLabs aidera \u00e0 offrir un traitement anticanc\u00e9reux cibl\u00e9 et personnalis\u00e9 \u00e0 des dizaines de milliers de patients canadiens atteints de cancer, gr\u00e2ce au profilage g\u00e9nomique des tumeurs, une analyse d\u2019avant-garde qui peut sauver des vies ici \u00e0 Toronto et ailleurs au pays. \u00bb<\/p>\n<p>\u2013 M. Bernard Trottier, secr\u00e9taire parlementaire du ministre des Affaires \u00e9trang\u00e8res et pour la Francophonie et d\u00e9put\u00e9 d\u2019Etobicoke-Lakeshore<\/p>\n<p>\u00ab La g\u00e9nomique offre beaucoup de potentiel de nouvelles id\u00e9es et d\u2019innovations applicables dans plusieurs secteurs d\u2019importance vitale pour le Canada. Nous sommes heureux de voir de si nombreux \u201cutilisateurs\u201d de la g\u00e9nomique d\u00e9sireux de travailler en partenariat avec des chercheurs pour transformer la recherche en g\u00e9nomique en applications pratiques. \u00bb<\/p>\n<p>\u2013 M. Lorne Hepworth, pr\u00e9sident d\u2019assembl\u00e9e de G\u00e9nome Canada<\/p>\n<p>\u00ab Nous sommes tr\u00e8s heureux d\u2019avoir l\u2019occasion de collaborer avec LifeLabs et de favoriser la synergie entre nos points forts et notre expertise respectifs pour que la technologie g\u00e9nomique soit int\u00e9gr\u00e9e aux soins cliniques courants, a d\u00e9clar\u00e9 Dre Kamel-Reid. Nous voulons am\u00e9liorer les soins aux patients en augmentant l\u2019acc\u00e8s au profilage g\u00e9nomique et en personnalisant les traitements pour toutes les Canadiennes et tous les Canadiens. Par ce financement, G\u00e9nome Canada nous aide \u00e0 nous rapprocher de cet objectif. \u00bb<\/p>\n<p>\u2013 Dre Suzanne Kamel-Reid, chef de la G\u00e9n\u00e9tique, Laboratoire clinique, et directrice, Diagnostics mol\u00e9culaires, R\u00e9seau universitaire de la sant\u00e9<\/p>\n<p>\u00ab Nous sommes tr\u00e8s heureux de nous associer au Princess Margaret Cancer Centre et au R\u00e9seau universitaire de la sant\u00e9 pour le profilage g\u00e9nomique de sp\u00e9cimens de cancer. La combinaison des forces de LifeLabs en mati\u00e8re de collecte de sp\u00e9cimens, de r\u00e9seau de transport, de capacit\u00e9s logistiques et de possibilit\u00e9s grandissantes concernant les tests g\u00e9n\u00e9tiques et de l\u2019expertise du PMCC, qui est le principal concepteur au Canada de nouveaux tests g\u00e9nomiques du cancer, fait de ce projet une collaboration incroyable. Mettre en place une strat\u00e9gie nationale pour le profilage g\u00e9nomique de sp\u00e9cimens de cancer est une \u00e9tape cruciale pour que les patients canadiens atteints de cancer aient acc\u00e8s aux soins les plus efficaces. Nous sommes tr\u00e8s reconnaissants du leadership et du soutien de G\u00e9nome Canada. \u00bb<\/p>\n<p>\u2013 M. Jeff Sumner, vice-pr\u00e9sident principal, D\u00e9veloppement des affaires, Affaires cliniques et G\u00e9n\u00e9tique<\/p>\n<p><strong>Liens connexes<\/strong><\/p>\n<p><a href=\"http:\/\/www.genomecanada.ca\/medias\/pdf\/fr\/gapp-backgrounder-round3-projects_FR.pdf\">Fiche d\u2019information<\/a>&nbsp;\u2013 Projets de la 3e s\u00e9rie du PPAG&nbsp;<br \/>\n<a href=\"https:\/\/www.youtube.com\/watch?v=mV7b0cB-ago&amp;list=PL0Qjr5jwSHg5eKYDXjHUvFWSQOpVRpggm&amp;index=2\">Vid\u00e9o<\/a>&nbsp;\u2013 Pierre Meulien au sujet du PPAG&nbsp;<br \/>\n<a href=\"http:\/\/www.genomecanada.ca\/fr\/nouvelles-et-evenements\/nouvelles\/le-gouvernement-du-canada-annonce-de-nouveaux-projets-de-recherche\">Communiqu\u00e9<\/a>&nbsp;des s\u00e9ries 1 et 2 du PPAG, 15 octobre 2014&nbsp;<br \/>\n<a href=\"http:\/\/www.genomecanada.ca\/fr\/nouvelles-et-evenements\/nouvelles\/le-gouvernement-harper-et-genome-canada-annoncent-la-creation-dun\">Communiqu\u00e9<\/a>&nbsp;du lancement du PPAG, 3 juin 2013<\/p>\n<p>Suivez-nous sur Twitter @GenomeCanada;&nbsp;<a href=\"https:\/\/twitter.com\/industrycanada\">@industrycanada<\/a><\/p>\n<p><strong>Renseignements<\/strong><\/p>\n<p>Scott French Directeur, Communications et Affaires parlementaires&nbsp;<br \/>\nCabinet du ministre d\u2019\u00c9tat (Sciences et Technologie)&nbsp;<br \/>\n613-943-6177<\/p>\n<p>Andrea Matyas&nbsp;<br \/>\nDirectrice, Communications&nbsp;<br \/>\nG\u00e9nome Canada&nbsp;<br \/>\nBureau : 613-751-4460, p. 231&nbsp;<br \/>\nCellulaire : 613-790-0106<\/p>\n<p><strong>\u00c0 propos de G\u00e9nome Canada :&nbsp;<\/strong><a href=\"http:\/\/www.genomecanada.ca\/\"><strong>www.genomecanada.ca<\/strong><\/a><\/p>\n<p>G\u00e9nome Canada est une soci\u00e9t\u00e9 sans but lucratif qui sert de catalyseur de la mise en valeur et de l\u2019application de la g\u00e9nomique et des technologies qui s\u2019y rattachent au profit de la population canadienne qui en retirera des avantages \u00e9conomiques et sociaux. Ses fonctions sont multiples : relier id\u00e9es et personnes des secteurs public et priv\u00e9 pour trouver de nouveaux usages \u00e0 la g\u00e9nomique; investir dans les sciences et la technologie de grande envergure pour stimuler l\u2019innovation; et transformer les d\u00e9couvertes en applications et en solutions dans les secteurs cl\u00e9s d\u2019importance nationale, soit la sant\u00e9, l\u2019agriculture, la foresterie, les p\u00eaches et l\u2019aquaculture, l\u2019\u00e9nergie, les mines et l\u2019environnement.<\/p>\n<p><strong>\u00c0 propos sur R\u00e9seau universitaire de la sant\u00e9 :&nbsp;<\/strong><a href=\"http:\/\/www.uhn.ca\/\"><strong>www.uhn.ca<\/strong><\/a><\/p>\n<p>Le R\u00e9seau universitaire de la sant\u00e9 comprend les h\u00f4pitaux Toronto General et Toronto Western, le Princess Margaret Cancer Centre et le Toronto Rehabilitation Institute. L\u2019ampleur des recherches et la complexit\u00e9 des cas que traitent les membres du R\u00e9seau en ont fait une source nationale et internationale de d\u00e9couverte, d\u2019\u00e9ducation et de soins aux patients. Il s\u2019agit du plus grand programme canadien de recherches en milieu hospitalier et des travaux sont effectu\u00e9s dans les domaines de la cardiologie, des transplantations, des neurosciences, de l\u2019oncologie, de l\u2019innovation chirurgicale, des maladies infectieuses, de la m\u00e9decine g\u00e9nomique et de la m\u00e9decine de r\u00e9adaptation. Le R\u00e9seau universitaire de la sant\u00e9 est un r\u00e9seau d\u2019h\u00f4pitaux affili\u00e9 \u00e0 l\u2019Universit\u00e9 de Toronto. (En anglais seulement)<\/p>\n<p><strong>\u00c0 propos de LifeLabs :&nbsp;<\/strong><a href=\"http:\/\/www.lifelabs.com\/\"><strong>www.LifeLabs.com<\/strong><\/a><\/p>\n<p>LifeLabs est une soci\u00e9t\u00e9 canadienne qui compte plus de 50 ans d\u2019exp\u00e9rience dans la prestation de services de tests en laboratoire qui aident les professionnels de la sant\u00e9 \u00e0 porter des diagnostics, \u00e0 traiter, \u00e0 surveiller et \u00e0 pr\u00e9venir les maladies. LifeLabs assure, dans des communaut\u00e9s de la Colombie-Britannique et de l\u2019Ontario, l\u2019acc\u00e8s \u00e9conomique et commode \u00e0 des services de tests en laboratoire essentiels \u00e0 des r\u00e9sultats optimaux en sant\u00e9. LifeLabs emploie environ 5 400 personnes de formation professionnelle, livre plus de 100 millions de tests de laboratoire et enregistre 19 millions de visites de patients par ann\u00e9e. En 2013, LifeLabs a fait l\u2019acquisition de BC Biomedical en Colombie-Britannique et de CML HealthCare en Ontario, devenant ainsi le plus grand groupe de laboratoires au Canada. LifeLabs appartient indirectement \u00e0 OMERS Administration Corporation, dont la participation financi\u00e8re est g\u00e9r\u00e9e par Borealis Infrastructure. Pour en savoir plus sur LifeLabs Genetics, visitez&nbsp;<a href=\"http:\/\/www.lifelabsgenetics.com\/\">www.LifeLabsGenetics.com<\/a>.&nbsp;<strong>LifeLabs est un fier commanditaire des Jeux panam\u00e9ricains et parapanam\u00e9ricains de 2015 \u00e0 Toronto<\/strong>. (En anglais seulement)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des milliers de patients canadiens atteints de cancer pourraient bient\u00f4t b\u00e9n\u00e9ficier d\u2019un traitement plus cibl\u00e9 et personnalis\u00e9 gr\u00e2ce \u00e0 un investissement de G\u00e9nome Canada. L\u2019honorable Ed Holder, ministre d\u2019\u00c9tat (Sciences et Technologie) et M. Bernard Trottier, d\u00e9put\u00e9 d\u2019Etobicoke Lakeshore, accompagn\u00e9s de M. Lorne Hepworth, pr\u00e9sident d\u2019assembl\u00e9e de G\u00e9nome Canada, ont annonc\u00e9 l\u2019investissement de pr\u00e8s de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[127],"tags":[],"mission-categories":[],"class_list":["post-1454","post","type-post","status-publish","format-standard","hentry","category-news-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>De nouveaux projets de recherche en g\u00e9nomique cr\u00e9eront des avantages \u00e9conomiques et sociaux pour la population canadienne - GenomeCanada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/genomecanada.ca\/fr\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De nouveaux projets de recherche en g\u00e9nomique cr\u00e9eront des avantages \u00e9conomiques et sociaux pour la population canadienne - GenomeCanada\" \/>\n<meta property=\"og:description\" content=\"Des milliers de patients canadiens atteints de cancer pourraient bient\u00f4t b\u00e9n\u00e9ficier d\u2019un traitement plus cibl\u00e9 et personnalis\u00e9 gr\u00e2ce \u00e0 un investissement de G\u00e9nome Canada. L\u2019honorable Ed Holder, ministre d\u2019\u00c9tat (Sciences et Technologie) et M. Bernard Trottier, d\u00e9put\u00e9 d\u2019Etobicoke Lakeshore, accompagn\u00e9s de M. Lorne Hepworth, pr\u00e9sident d\u2019assembl\u00e9e de G\u00e9nome Canada, ont annonc\u00e9 l\u2019investissement de pr\u00e8s de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/genomecanada.ca\/fr\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\/\" \/>\n<meta property=\"og:site_name\" content=\"GenomeCanada\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-26T07:24:04+00:00\" \/>\n<meta name=\"author\" content=\"Pierre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\\\/\"},\"author\":{\"name\":\"Pierre\",\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/#\\\/schema\\\/person\\\/9178d2ca6aca04c78924c5863c96697a\"},\"headline\":\"De nouveaux projets de recherche en g\u00e9nomique cr\u00e9eront des avantages \u00e9conomiques et sociaux pour la population canadienne\",\"datePublished\":\"2015-12-26T07:24:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\\\/\"},\"wordCount\":1750,\"publisher\":{\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/#organization\"},\"articleSection\":[\"News\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\\\/\",\"url\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\\\/\",\"name\":\"De nouveaux projets de recherche en g\u00e9nomique cr\u00e9eront des avantages \u00e9conomiques et sociaux pour la population canadienne - GenomeCanada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/#website\"},\"datePublished\":\"2015-12-26T07:24:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De nouveaux projets de recherche en g\u00e9nomique cr\u00e9eront des avantages \u00e9conomiques et sociaux pour la population canadienne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/\",\"name\":\"GenomeCanada\",\"description\":\"Harnessing the transformative power of genomics\",\"publisher\":{\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/#organization\",\"name\":\"GenomeCanada\",\"url\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/genomecanada.ca\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/genome-canada_stacked.svg\",\"contentUrl\":\"https:\\\/\\\/genomecanada.ca\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/genome-canada_stacked.svg\",\"width\":285,\"height\":180,\"caption\":\"GenomeCanada\"},\"image\":{\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/#\\\/schema\\\/person\\\/9178d2ca6aca04c78924c5863c96697a\",\"name\":\"Pierre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a57e4d6e69393a17b8cd7f6418130969ad93131795406009ba79ed41978382d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a57e4d6e69393a17b8cd7f6418130969ad93131795406009ba79ed41978382d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a57e4d6e69393a17b8cd7f6418130969ad93131795406009ba79ed41978382d2?s=96&d=mm&r=g\",\"caption\":\"Pierre\"},\"url\":\"https:\\\/\\\/genomecanada.ca\\\/fr\\\/author\\\/pierre\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De nouveaux projets de recherche en g\u00e9nomique cr\u00e9eront des avantages \u00e9conomiques et sociaux pour la population canadienne - GenomeCanada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/genomecanada.ca\/fr\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\/","og_locale":"fr_FR","og_type":"article","og_title":"De nouveaux projets de recherche en g\u00e9nomique cr\u00e9eront des avantages \u00e9conomiques et sociaux pour la population canadienne - GenomeCanada","og_description":"Des milliers de patients canadiens atteints de cancer pourraient bient\u00f4t b\u00e9n\u00e9ficier d\u2019un traitement plus cibl\u00e9 et personnalis\u00e9 gr\u00e2ce \u00e0 un investissement de G\u00e9nome Canada. L\u2019honorable Ed Holder, ministre d\u2019\u00c9tat (Sciences et Technologie) et M. Bernard Trottier, d\u00e9put\u00e9 d\u2019Etobicoke Lakeshore, accompagn\u00e9s de M. Lorne Hepworth, pr\u00e9sident d\u2019assembl\u00e9e de G\u00e9nome Canada, ont annonc\u00e9 l\u2019investissement de pr\u00e8s de [&hellip;]","og_url":"https:\/\/genomecanada.ca\/fr\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\/","og_site_name":"GenomeCanada","article_published_time":"2015-12-26T07:24:04+00:00","author":"Pierre","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Pierre","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/genomecanada.ca\/fr\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\/#article","isPartOf":{"@id":"https:\/\/genomecanada.ca\/fr\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\/"},"author":{"name":"Pierre","@id":"https:\/\/genomecanada.ca\/fr\/#\/schema\/person\/9178d2ca6aca04c78924c5863c96697a"},"headline":"De nouveaux projets de recherche en g\u00e9nomique cr\u00e9eront des avantages \u00e9conomiques et sociaux pour la population canadienne","datePublished":"2015-12-26T07:24:04+00:00","mainEntityOfPage":{"@id":"https:\/\/genomecanada.ca\/fr\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\/"},"wordCount":1750,"publisher":{"@id":"https:\/\/genomecanada.ca\/fr\/#organization"},"articleSection":["News"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/genomecanada.ca\/fr\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\/","url":"https:\/\/genomecanada.ca\/fr\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\/","name":"De nouveaux projets de recherche en g\u00e9nomique cr\u00e9eront des avantages \u00e9conomiques et sociaux pour la population canadienne - GenomeCanada","isPartOf":{"@id":"https:\/\/genomecanada.ca\/fr\/#website"},"datePublished":"2015-12-26T07:24:04+00:00","breadcrumb":{"@id":"https:\/\/genomecanada.ca\/fr\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/genomecanada.ca\/fr\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/genomecanada.ca\/fr\/de-nouveaux-projets-de-recherche-en-genomique-creeront-des-avantages-economiques-et\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/genomecanada.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"De nouveaux projets de recherche en g\u00e9nomique cr\u00e9eront des avantages \u00e9conomiques et sociaux pour la population canadienne"}]},{"@type":"WebSite","@id":"https:\/\/genomecanada.ca\/fr\/#website","url":"https:\/\/genomecanada.ca\/fr\/","name":"GenomeCanada","description":"Harnessing the transformative power of genomics","publisher":{"@id":"https:\/\/genomecanada.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/genomecanada.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/genomecanada.ca\/fr\/#organization","name":"GenomeCanada","url":"https:\/\/genomecanada.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/genomecanada.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/genomecanada.ca\/wp-content\/uploads\/2021\/07\/genome-canada_stacked.svg","contentUrl":"https:\/\/genomecanada.ca\/wp-content\/uploads\/2021\/07\/genome-canada_stacked.svg","width":285,"height":180,"caption":"GenomeCanada"},"image":{"@id":"https:\/\/genomecanada.ca\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/genomecanada.ca\/fr\/#\/schema\/person\/9178d2ca6aca04c78924c5863c96697a","name":"Pierre","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a57e4d6e69393a17b8cd7f6418130969ad93131795406009ba79ed41978382d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a57e4d6e69393a17b8cd7f6418130969ad93131795406009ba79ed41978382d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a57e4d6e69393a17b8cd7f6418130969ad93131795406009ba79ed41978382d2?s=96&d=mm&r=g","caption":"Pierre"},"url":"https:\/\/genomecanada.ca\/fr\/author\/pierre\/"}]}},"_links":{"self":[{"href":"https:\/\/genomecanada.ca\/fr\/wp-json\/wp\/v2\/posts\/1454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/genomecanada.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/genomecanada.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/genomecanada.ca\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/genomecanada.ca\/fr\/wp-json\/wp\/v2\/comments?post=1454"}],"version-history":[{"count":0,"href":"https:\/\/genomecanada.ca\/fr\/wp-json\/wp\/v2\/posts\/1454\/revisions"}],"wp:attachment":[{"href":"https:\/\/genomecanada.ca\/fr\/wp-json\/wp\/v2\/media?parent=1454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/genomecanada.ca\/fr\/wp-json\/wp\/v2\/categories?post=1454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/genomecanada.ca\/fr\/wp-json\/wp\/v2\/tags?post=1454"},{"taxonomy":"mission-categories","embeddable":true,"href":"https:\/\/genomecanada.ca\/fr\/wp-json\/wp\/v2\/mission-categories?post=1454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}